{"id":2723,"date":"2023-10-26T14:10:23","date_gmt":"2023-10-26T14:10:23","guid":{"rendered":"https:\/\/amplend.net\/?p=2723"},"modified":"2023-11-03T14:17:45","modified_gmt":"2023-11-03T14:17:45","slug":"9-elementos-que-afectan-a-las-condiciones-de-los-prestamos-de-alquiler-dscr","status":"publish","type":"post","link":"https:\/\/amplend.net\/es\/9-elementos-que-afectan-a-las-condiciones-de-los-prestamos-de-alquiler-dscr\/","title":{"rendered":"9 Elementos Que Afectan a las Condiciones de Los Pr\u00e9stamos de Alquiler DSCR"},"content":{"rendered":"<p class=\"gtfy-1\">Los prestamistas privados ofrecen pr\u00e9stamos DSCR (ratio de cobertura del servicio de la deuda) a los inversores con la estrategia de &#8220;comprar y mantener&#8221; dinero permanente a largo plazo en la estabilizaci\u00f3n. El programa de pr\u00e9stamos DSCR es una alternativa que los inversores pueden comparar con los programas de pr\u00e9stamos a largo plazo que ofrecen los prestamistas tradicionales.<\/p>\n\n\n\n<p class=\"gtfy-4\">Este art\u00edculo dar\u00e1 una visi\u00f3n general de los nueve elementos que afectan a la suscripci\u00f3n de un prestamista privado de un pr\u00e9stamo DSCR. Amplend entiende que los inversores inmobiliarios residenciales necesitan entender c\u00f3mo los prestamistas privados eval\u00faan los m\u00e9ritos de un acuerdo y los factores para lograr condiciones competitivas.<\/p>\n\n\n\n<p class=\"gtfy-7\"><strong>Puntos clave<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list gtfy-15\">\n<li class=\"gtfy-10 gutenify-list-item\">La puntuaci\u00f3n crediticia es el \u00fanico elemento de suscripci\u00f3n espec\u00edfico del inversor.<\/li>\n\n\n\n<li class=\"gtfy-11 gutenify-list-item\">Un pr\u00e9stamo DSCR es dinero permanente a largo plazo que ofrecen los prestamistas privados como alternativa a los programas que ofrecen los bancos tradicionales.<\/li>\n\n\n\n<li class=\"gtfy-12 gutenify-list-item\">El ratio de cobertura de la deuda es el elemento m\u00e1s importante que tiene en cuenta un prestamista privado a la hora de suscribir un pr\u00e9stamo DSCR.<\/li>\n\n\n\n<li class=\"gtfy-13 gutenify-list-item\">Un prestamista prestar\u00e1 m\u00e1s en la pila de capital y ofrecer\u00e1 una LTV m\u00e1s alta cuando el ratio DSCR supere su objetivo.<\/li>\n\n\n\n<li class=\"gtfy-14 gutenify-list-item\">El objetivo de un pr\u00e9stamo DSCR es acortar el tiempo de servicio de un pr\u00e9stamo a corto plazo y de alto inter\u00e9s, y obtener antes efectivo del capital incorporado.<\/li>\n<\/ul>\n\n\n\n<p class=\"gtfy-18\"><strong>T\u00e9rminos definidos<\/strong><\/p>\n\n\n\n<p class=\"gtfy-21\"><strong><em>Gastos por encima de la l\u00ednea:<\/em><\/strong> los gastos de explotaci\u00f3n aplicados a los ingresos por alquiler para calcular el NOI.<\/p>\n\n\n\n<p class=\"gtfy-24\"><strong><em>Gastos no operativos:<\/em><\/strong> los gastos no operativos aplicados a los ingresos por alquiler para calcular el flujo de caja, como el servicio de la deuda y la financiaci\u00f3n de las cuentas de reserva.<\/p>\n\n\n\n<p class=\"gtfy-27\"><strong><em>Capital acumulado:<\/em><\/strong> los componentes del importe del pr\u00e9stamo y el capital del inversor para totalizar el valor de mercado de la propiedad.<\/p>\n\n\n\n<p class=\"gtfy-30\"><strong>Los elementos decisivos<\/strong><\/p>\n\n\n\n<p class=\"gtfy-33\">Hay nueve elementos decisivos que los prestamistas privados utilizan para determinar el tipo y las condiciones de un pr\u00e9stamo DSCR. Estos elementos son<\/p>\n\n\n\n<ol class=\"wp-block-list gtfy-45\" type=\"1\">\n<li class=\"gtfy-36 gutenify-list-item\">Ratio de cobertura del servicio de la deuda,<\/li>\n\n\n\n<li class=\"gtfy-37 gutenify-list-item\">Apalancamiento,<\/li>\n\n\n\n<li class=\"gtfy-38 gutenify-list-item\">Puntuaci\u00f3n crediticia,<\/li>\n\n\n\n<li class=\"gtfy-39 gutenify-list-item\">Comisi\u00f3n de apertura,<\/li>\n\n\n\n<li class=\"gtfy-40 gutenify-list-item\">Penalizaci\u00f3n por pago anticipado,<\/li>\n\n\n\n<li class=\"gtfy-41 gutenify-list-item\">Tipo de inter\u00e9s,<\/li>\n\n\n\n<li class=\"gtfy-42 gutenify-list-item\">Tipo de propiedad,<\/li>\n\n\n\n<li class=\"gtfy-43 gutenify-list-item\">Tama\u00f1o del pr\u00e9stamo, y<\/li>\n\n\n\n<li class=\"gtfy-44 gutenify-list-item\">Tipo de pr\u00e9stamo.<\/li>\n<\/ol>\n\n\n\n<p class=\"gtfy-48\"><strong>Objetivos del pr\u00e9stamo DSCR<\/strong><\/p>\n\n\n\n<p class=\"gtfy-51\">La suscripci\u00f3n de un pr\u00e9stamo DSCR a largo plazo para inmuebles estabilizados es m\u00e1s diligente que la suscripci\u00f3n de un pr\u00e9stamo de adquisici\u00f3n y renovaci\u00f3n a corto plazo. Sin embargo, un prestamista privado mantiene su esp\u00edritu empresarial en este proceso, y el tiempo entre la solicitud y la financiaci\u00f3n sigue siendo m\u00e1s corto que el de un prestamista tradicional.<\/p>\n\n\n\n<p class=\"gtfy-54\">Los objetivos de un pr\u00e9stamo DSCR son acortar el tiempo en que el inversor atiende el pr\u00e9stamo a corto plazo, de mayor inter\u00e9s, y obtener antes los beneficios del capital creado por las renovaciones.<\/p>\n\n\n\n<p class=\"gtfy-57\">Teniendo esto en cuenta, repasemos cada uno de los elementos anteriores.<\/p>\n\n\n\n<p class=\"gtfy-60\"><strong>Coeficiente de cobertura del servicio de la deuda<\/strong><\/p>\n\n\n\n<p class=\"gtfy-63\">Este es el ratio m\u00e1s importante que tiene en cuenta un prestamista privado a la hora de suscribir una propiedad estabilizada. La f\u00f3rmula de este ratio es<\/p>\n\n\n\n<p class=\"gtfy-66\"><strong>NOI (ingresos netos de explotaci\u00f3n) \u00f7 ADS (servicio anual de la deuda)<\/strong><\/p>\n\n\n\n<p class=\"gtfy-69\">Por ejemplo, si el ADS (principal e intereses solamente) es de 24.000 $, o 2.000 $ al mes, y el NOI de la propiedad es de 30.000 $, o 2.500 $ al mes, entonces<\/p>\n\n\n\n<p class=\"gtfy-72\"><strong>$30,000 \u00f7 $24,000 = 1.25<\/strong><\/p>\n\n\n\n<p class=\"gtfy-75\">La traducci\u00f3n de este ratio es la disponibilidad de 1,25 $ de ingresos netos (alquiler menos gastos) por cada 1 $ de servicio de la deuda.<\/p>\n\n\n\n<p class=\"gtfy-78\">Sin embargo, cuando un inversor realiza este c\u00e1lculo para su propia diligencia debida, debe prestar atenci\u00f3n a los pagos del pr\u00e9stamo que contienen la financiaci\u00f3n de una cuenta de garant\u00eda bloqueada para los impuestos sobre la propiedad y el seguro.<\/p>\n\n\n\n<p class=\"gtfy-81\">Recuerde que los pagos hipotecarios del principal y los intereses no entran en la definici\u00f3n de gastos de explotaci\u00f3n, pero los impuestos sobre la propiedad y el seguro se cargan por encima de la l\u00ednea. Hay que tener cuidado para asegurarse de que estos gastos no se contabilizan dos veces: una vez por encima de la l\u00ednea como gastos y otra vez por debajo de la l\u00ednea como parte del servicio de la deuda.<\/p>\n\n\n\n<p class=\"gtfy-84\">El ratio de cobertura de 1,25 calculado anteriormente est\u00e1 por encima del ratio objetivo est\u00e1ndar del sector de 1,15. Un prestamista privado ofrecer\u00e1 condiciones de pr\u00e9stamo competitivas a los inmuebles que superen su ratio objetivo. Cuanto mayor sea el ratio, menor ser\u00e1 el riesgo percibido.<\/p>\n\n\n\n<p class=\"gtfy-87\"><strong>Apalancamiento<\/strong><\/p>\n\n\n\n<p class=\"gtfy-90\">El ratio de cobertura del servicio de la deuda es importante cuando un prestamista privado considera el apalancamiento. Cuando un prestamista percibe menos riesgo, est\u00e1 dispuesto a prestar m\u00e1s capital.<\/p>\n\n\n\n<p class=\"gtfy-93\">El apalancamiento es un porcentaje del importe del pr\u00e9stamo respecto al valor de mercado de la propiedad. Este porcentaje tambi\u00e9n se conoce como relaci\u00f3n pr\u00e9stamo-valor (LTV). Un inversor recibir\u00e1 menos efectivo en un pr\u00e9stamo con una LTV del 60% que en un pr\u00e9stamo con una LTV del 70%. Cuanto mayor sea la LTV, m\u00e1s efectivo estar\u00e1 dispuesto a financiar un prestamista debido a la menor percepci\u00f3n del riesgo. El riesgo est\u00e1 relacionado con el ratio de cobertura de la deuda y el apalancamiento.<\/p>\n\n\n\n<p class=\"gtfy-96\">La f\u00f3rmula para calcular el apalancamiento es<\/p>\n\n\n\n<p class=\"gtfy-99\"><strong>Importe del pr\u00e9stamo \u00f7 Valor de mercado<\/strong><\/p>\n\n\n\n<p class=\"gtfy-102\">Por ejemplo, si el valor de mercado de una propiedad es de 200.000 $ y un prestamista est\u00e1 dispuesto a prestar hasta el 70%, entonces<\/p>\n\n\n\n<p class=\"gtfy-105\"><strong>200.000 $ x 0,7 = 140.000 $, entonces<\/strong><\/p>\n\n\n\n<p class=\"gtfy-108\"><strong>140.000 $ \u00f7 200.000 $ = 0,7, es decir, el 70%.<\/strong><\/p>\n\n\n\n<p class=\"gtfy-111\">El t\u00e9rmino &#8220;pila de capital&#8221; en este ejemplo es la suma del importe del pr\u00e9stamo y el capital del inversor es la &#8220;pila&#8221; que comprende el valor total de mercado. Para ilustrarlo:<\/p>\n\n\n\n<figure class=\"wp-block-table gtfy-114\"><table><tbody><tr><td>$140,000<\/td><td>Monto del pr\u065e\u00e9stamo<\/td><\/tr><tr><td>+&nbsp; 60,000<\/td><td>Fondos propios de los inversores<\/td><\/tr><tr><td>$200,000<\/td><td>Valor de mercado<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"gtfy-117\">Por tanto, cuanto mayor sea el ratio LTV, m\u00e1s lejos en la pila de capital estar\u00e1 dispuesto a invertir un prestamista. Esto se traduce en una mayor salida de efectivo para el inversor debido a la menor percepci\u00f3n del riesgo.<\/p>\n\n\n\n<p class=\"gtfy-120\">Con un pr\u00e9stamo DSCR garantizado por una propiedad estabilizada, los ratios de suscripci\u00f3n se basan en el valor de mercado, a diferencia de los pr\u00e9stamos a corto plazo, en los que los ratios se basan en el coste. Existe un capital incorporado cuando el valor de las mejoras supera los costes.<\/p>\n\n\n\n<p class=\"gtfy-123\"><strong>Puntuaci\u00f3n crediticia<\/strong><\/p>\n\n\n\n<p class=\"gtfy-126\">La puntuaci\u00f3n crediticia del inversor tendr\u00e1 m\u00e1s peso a la hora de suscribir un pr\u00e9stamo DSCR que un pr\u00e9stamo de adquisici\u00f3n a corto plazo. La puntuaci\u00f3n crediticia es verificable y una forma r\u00e1pida de medir el riesgo para el prestamista. La puntuaci\u00f3n crediticia es el \u00fanico elemento de los nueve que se refiere directa y exclusivamente al inversor.<\/p>\n\n\n\n<p class=\"gtfy-129\">Los otros ocho elementos se centran en el rendimiento de la propiedad y la tolerancia al riesgo del prestamista.<\/p>\n\n\n\n<p class=\"gtfy-132\">La puntuaci\u00f3n crediticia afecta directamente al tipo de inter\u00e9s y al apalancamiento.<\/p>\n\n\n\n<p class=\"gtfy-135\">La mejor manera de que un inversor consiga un tipo competitivo y un mayor LTC es mejorar su puntuaci\u00f3n crediticia. La mejora de la puntuaci\u00f3n crediticia tiene dos vertientes: efectuar puntualmente los pagos de todas las obligaciones y controlar que no haya errores en el informe crediticio.<\/p>\n\n\n\n<p class=\"gtfy-138\"><strong>Comisiones de apertura<\/strong><\/p>\n\n\n\n<p class=\"gtfy-141\">La comisi\u00f3n de apertura se expresa como un porcentaje del importe del pr\u00e9stamo que se cobra para cubrir los costes directos del prestamista por tramitar la solicitud, suscribir la operaci\u00f3n y administrar el pr\u00e9stamo. Normalmente, la comisi\u00f3n de apertura de un pr\u00e9stamo DSCR con un ratio de cobertura aceptable se sit\u00faa entre el 0,5% y el 1% del importe del pr\u00e9stamo.<\/p>\n\n\n\n<p class=\"gtfy-144\">Las comisiones de apertura tambi\u00e9n se conocen como comisiones de descuento o puntos.<\/p>\n\n\n\n<p class=\"gtfy-147\">Regla general: un prestamista privado de confianza cobrar\u00e1 una comisi\u00f3n de apertura en el momento del cierre y no exigir\u00e1 ning\u00fan pago antes de la tramitaci\u00f3n o la suscripci\u00f3n.<\/p>\n\n\n\n<p class=\"gtfy-150\">La comisi\u00f3n de apertura de un pr\u00e9stamo DSCR a largo plazo ser\u00e1 inferior a la de un pr\u00e9stamo de adquisici\u00f3n a corto plazo garantizado por una propiedad vacante y en dificultades.<\/p>\n\n\n\n<p class=\"gtfy-153\">\u00bfPuede negociarse una comisi\u00f3n de apertura? Tal vez, pero cualquier reducci\u00f3n se traducir\u00e1 en un tipo de inter\u00e9s m\u00e1s alto.<\/p>\n\n\n\n<p class=\"gtfy-156\">Es importante saber que las comisiones de apertura forman parte de la tasa anual equivalente (TAE) para reflejar el coste total del capital. La comisi\u00f3n de apertura y otras comisiones asociadas al pr\u00e9stamo se suman al tipo de inter\u00e9s. El tipo de inter\u00e9s s\u00f3lo refleja el coste de tomar prestado el capital.<\/p>\n\n\n\n<p class=\"gtfy-159\"><strong>Penalizaci\u00f3n por pago anticipado<\/strong><\/p>\n\n\n\n<p class=\"gtfy-162\">Los prestamistas cobran una penalizaci\u00f3n por pago anticipado para estabilizar su rentabilidad. Los prestamistas son inversores, y las inversiones se realizan con un n\u00famero predeterminado de pagos. Los pagos del pr\u00e9stamo son el retorno de y sobre el capital invertido para financiar las operaciones y aumentar el efectivo disponible para invertir en otras oportunidades.<\/p>\n\n\n\n<p class=\"gtfy-165\">Los beneficios y el efectivo disponible se reducen si un pr\u00e9stamo se paga demasiado pronto en el plazo. La penalizaci\u00f3n por pago anticipado estabiliza el pr\u00e9stamo y garantiza el beneficio.<\/p>\n\n\n\n<p class=\"gtfy-168\">Generalmente, esta penalizaci\u00f3n est\u00e1 en vigor durante los primeros 5-8 a\u00f1os del plazo, y la penalizaci\u00f3n puede oscilar entre el 1% y el 5% del saldo pendiente. Por lo tanto, la penalizaci\u00f3n reduce el riesgo del prestamista, y su aplicaci\u00f3n mejorar\u00e1 el precio del pr\u00e9stamo con un tipo de inter\u00e9s m\u00e1s bajo y una LTV m\u00e1s alta.<\/p>\n\n\n\n<p class=\"gtfy-171\">Esta penalizaci\u00f3n puede ayudar al inversor a calcular la rentabilidad de su inversi\u00f3n. Cuando un inversor conoce el importe total de satisfacci\u00f3n en una refinanciaci\u00f3n o una venta, el rendimiento es exacto. Si un inversor planea conservar la propiedad durante m\u00e1s tiempo que el periodo de vigencia de la penalizaci\u00f3n, entonces la rentabilidad es mayor, y la penalizaci\u00f3n no es un problema.<\/p>\n\n\n\n<p class=\"gtfy-174\">Una penalizaci\u00f3n por pago anticipado es un buen &#8220;regalo&#8221; para obtener un tipo de inter\u00e9s m\u00e1s bajo y una relaci\u00f3n pr\u00e9stamo-valor m\u00e1s alta sin que la penalizaci\u00f3n afecte a la estrategia de salida.<\/p>\n\n\n\n<p class=\"gtfy-177\"><strong>Tipo de inter\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"gtfy-180\">Una de las ventajas de un pr\u00e9stamo DSCR a largo plazo sobre una propiedad estabilizada es la posibilidad de elegir la estructura del tipo de inter\u00e9s. Aunque el tipo ofrecido sigue estando en funci\u00f3n del riesgo, la estructura del tipo puede variar. Las opciones de estructura m\u00e1s comunes que ofrecen los prestamistas privados en propiedades residenciales de alquiler son:<\/p>\n\n\n\n<ul class=\"wp-block-list gtfy-187\">\n<li class=\"gtfy-183 gutenify-list-item\">5\/6 ARM (hipoteca de tipo variable),<\/li>\n\n\n\n<li class=\"gtfy-184 gutenify-list-item\">7\/6 ARM,<\/li>\n\n\n\n<li class=\"gtfy-185 gutenify-list-item\">fijo a 30 a\u00f1os, y<\/li>\n\n\n\n<li class=\"gtfy-186 gutenify-list-item\">s\u00f3lo inter\u00e9s.<\/li>\n<\/ul>\n\n\n\n<p class=\"gtfy-190\">A medida que se revisa cada tipo de tasa a continuaci\u00f3n, tenga en cuenta que la tasa cotizada sigue siendo el resultado de la suscripci\u00f3n del prestamista y su medici\u00f3n del riesgo. Aunque este tipo de inter\u00e9s no puede ser objeto de negociaci\u00f3n, la elecci\u00f3n del tipo de inter\u00e9s puede quedar a discreci\u00f3n del inversor en funci\u00f3n del periodo de mantenimiento y de las condiciones del mercado.<\/p>\n\n\n\n<p class=\"gtfy-193\"><strong>ARM 5\/6<\/strong><\/p>\n\n\n\n<p class=\"gtfy-196\">Los dos \u00edndices utilizados por los prestamistas para fijar el tipo inicial de un ARM son el tipo preferente de Estados Unidos y el tipo del Tesoro a vencimiento constante. El tipo preferente lo fijan los bancos comerciales y lo ofrecen a sus clientes m\u00e1s solventes. El tipo del Tesoro a vencimiento constante lo fija el Consejo de la Reserva Federal y representa el rendimiento a un a\u00f1o de sus valores subastados. El tipo fijado por la Junta de la Reserva Federal est\u00e1 eliminando progresivamente el uso del LIBOR.<\/p>\n\n\n\n<p class=\"gtfy-199\">La referencia &#8220;5\/6&#8221; significa que el tipo de inter\u00e9s cotizado por el prestamista permanecer\u00e1 fijo durante los cinco primeros a\u00f1os del plazo del pr\u00e9stamo. Despu\u00e9s, el tipo se ajustar\u00e1 cada seis meses hasta que el pr\u00e9stamo venza o se satisfaga. Puede existir la posibilidad de negociar un l\u00edmite m\u00e1ximo del tipo de inter\u00e9s en los momentos de ajuste.<\/p>\n\n\n\n<p class=\"gtfy-202\">Un pr\u00e9stamo ARM 5\/6 podr\u00eda beneficiar a un inversor si el per\u00edodo de mantenimiento previsto es inferior al per\u00edodo de tipo bajo fijo. La clave de esta consideraci\u00f3n es la penalizaci\u00f3n por pago anticipado durante los primeros cinco a\u00f1os, cuando el tipo fijo bajo est\u00e1 en vigor.<\/p>\n\n\n\n<p class=\"gtfy-205\"><strong>ARM 7\/6<\/strong><\/p>\n\n\n\n<p class=\"gtfy-208\">Los conceptos en los que se basa una hipoteca ARM 7\/6 son los mismos que los de la ARM 5\/6, pero con un tipo de inter\u00e9s fijo durante los primeros siete a\u00f1os del plazo. A partir de entonces, se har\u00e1n ajustes cada seis meses hasta que el pr\u00e9stamo venza o sea satisfecho. El tipo de inter\u00e9s fijo de una hipoteca ARM 7\/6 suele ser m\u00e1s bajo que el de una ARM 5\/6, y puede haber margen para negociar la penalizaci\u00f3n por pago anticipado.<\/p>\n\n\n\n<p class=\"gtfy-211\">El inversor debe hacer todo lo posible por negociar un tope en los ajustes y debe tener en cuenta el per\u00edodo de retenci\u00f3n de la propiedad.<\/p>\n\n\n\n<p class=\"gtfy-214\">La clave es que la penalizaci\u00f3n por pago anticipado no supere el ahorro de intereses obtenido durante el primer per\u00edodo de siete a\u00f1os, cuando el tipo puede estar en su punto m\u00e1s bajo.<\/p>\n\n\n\n<p class=\"gtfy-217\"><strong>Fijo a 30 a\u00f1os<\/strong><\/p>\n\n\n\n<p class=\"gtfy-220\">Este tipo de inter\u00e9s es la estructura habitual para las propiedades ocupadas por sus propietarios.<\/p>\n\n\n\n<p class=\"gtfy-223\">En cualquier pr\u00e9stamo a tipo fijo, el tipo de inter\u00e9s permanece fijo durante todo el plazo del pr\u00e9stamo. El tipo no se ajustar\u00e1 en ning\u00fan momento a lo largo del pr\u00e9stamo. El pr\u00e9stamo se amortiza en un periodo de 30 a\u00f1os, pero el plazo puede ser de 15 \u00f3 20 a\u00f1os. Esta estructura se conoce como hipoteca globo, en la que el \u00faltimo pago ser\u00e1 significativamente m\u00e1s alto porque el pr\u00e9stamo vence antes de que se autoamortice a un saldo de 0 $.<\/p>\n\n\n\n<p class=\"gtfy-226\">Si no existen penalizaciones por pago anticipado para una hipoteca a tipo fijo a 30 a\u00f1os, se producir\u00e1 un ajuste al alza en el tipo de inter\u00e9s indicado.<\/p>\n\n\n\n<p class=\"gtfy-229\"><strong>S\u00f3lo inter\u00e9s<\/strong><\/p>\n\n\n\n<p class=\"gtfy-232\">Un pr\u00e9stamo de s\u00f3lo intereses es exactamente como se define. Los pagos del pr\u00e9stamo s\u00f3lo cubren los intereses, y el saldo del capital permanece inalterado.<\/p>\n\n\n\n<p class=\"gtfy-235\">Los tipos de los pr\u00e9stamos de s\u00f3lo intereses tienden a ser m\u00e1s altos que los de amortizaci\u00f3n y los coeficientes LTV son m\u00e1s bajos. Un prestamista percibe estos pr\u00e9stamos como m\u00e1s arriesgados y no prestar\u00e1 demasiado.<\/p>\n\n\n\n<p class=\"gtfy-238\">Un inversor que busca un pr\u00e9stamo de s\u00f3lo intereses sobre dinero permanente a largo plazo est\u00e1 apostando realmente por un mercado fuerte al final de su periodo de tenencia. Si el mercado se mantiene fuerte, entonces un pr\u00e9stamo de s\u00f3lo intereses podr\u00eda ser una buena estrategia, ya que el principal se mantiene bajo en relaci\u00f3n con la revalorizaci\u00f3n del mercado.<\/p>\n\n\n\n<p class=\"gtfy-241\">La estrategia consiste en vender la propiedad antes de que el mercado gire y los valores disminuyan.<\/p>\n\n\n\n<p class=\"gtfy-244\"><strong>Tipo de propiedad<\/strong><\/p>\n\n\n\n<p class=\"gtfy-247\">Los prestamistas privados que se dirigen a inversores residenciales con el modelo de crear valor consideran que una propiedad con una estructura unifamiliar aislada es la menos arriesgada. Estos prestamistas privados s\u00f3lo tienen tolerancia al riesgo para inmuebles de categor\u00eda A en mercados primarios de primer orden. Estos prestamistas no prestan en oportunidades de valor a\u00f1adido.<\/p>\n\n\n\n<p class=\"gtfy-250\">Sin embargo, los prestamistas privados que se centran en el inversor de valor a\u00f1adido suscribir\u00e1n una propiedad &#8220;B&#8221; o &#8220;C&#8221; en ubicaciones de segundo nivel con potencial de valor. Estos prestamistas suscriben un valor despu\u00e9s de la reparaci\u00f3n (ARV).<\/p>\n\n\n\n<p class=\"gtfy-253\">Un prestamista ofrecer\u00e1 los mejores tipos de inter\u00e9s a los inversores en propiedades unifamiliares. Estas propiedades son m\u00e1s f\u00e1ciles de gestionar y tienen un tiempo m\u00e1s corto en el mercado antes de una venta. Los prestamistas prefieren un solo inquilino con una sola serie de problemas.<\/p>\n\n\n\n<p class=\"gtfy-256\">Las propiedades residenciales se definen como viviendas unifamiliares de 1 a 4 unidades. Mientras que las propiedades con m\u00faltiples unidades pueden parecer mejores para la proforma de un inversor en t\u00e9rminos de flujo de caja, los prestamistas suscribir\u00e1n a un mayor riesgo, y el riesgo se reflejar\u00e1 en la tasa de inter\u00e9s y el LTV.<\/p>\n\n\n\n<p class=\"gtfy-259\"><strong>Tama\u00f1o del pr\u00e9stamo<\/strong><\/p>\n\n\n\n<p class=\"gtfy-262\">El tama\u00f1o de un pr\u00e9stamo y su efecto en el tipo de inter\u00e9s es subjetivo. En general, un prestamista aumentar\u00e1 su tipo de inter\u00e9s entre 25 y 100 puntos b\u00e1sicos si el importe del pr\u00e9stamo es demasiado peque\u00f1o o demasiado grande.<\/p>\n\n\n\n<p class=\"gtfy-265\">Para los prestamistas privados interesados en oportunidades de valor a\u00f1adido, los pr\u00e9stamos de un importe comprendido entre 200.000 y 1,49 millones de d\u00f3lares son los m\u00e1s convenientes. Esta gama no suele estar sujeta a ning\u00fan ajuste del presupuesto suscrito.<\/p>\n\n\n\n<p class=\"gtfy-268\">Aunque un pr\u00e9stamo &#8220;peque\u00f1o&#8221; puede ser menos arriesgado para un prestamista en t\u00e9rminos de desembolso de capital, los prestamistas tienen costes fijos de tramitaci\u00f3n, suscripci\u00f3n y administraci\u00f3n de un pr\u00e9stamo. Un pr\u00e9stamo de 50.000 d\u00f3lares tendr\u00e1 los mismos costes que uno de 5 millones. El aumento de la TAE parecer\u00e1 desproporcionado cuando estas cantidades fijas se carguen a pr\u00e9stamos peque\u00f1os.<\/p>\n\n\n\n<p class=\"gtfy-271\">Como afirmaci\u00f3n general, los pr\u00e9stamos grandes son m\u00e1s arriesgados para los prestamistas privados que se dirigen a inversores residenciales de valor a\u00f1adido.<\/p>\n\n\n\n<p class=\"gtfy-274\"><strong>Tipo de pr\u00e9stamo<\/strong><\/p>\n\n\n\n<p class=\"gtfy-277\">Este elemento se basa en los otros elementos correspondientes de apalancamiento, tipo de tipo de inter\u00e9s, tipo de propiedad y tama\u00f1o del pr\u00e9stamo. Los elementos externos a un pr\u00e9stamo DSCR son el objetivo de rentabilidad del inversor y la duraci\u00f3n del per\u00edodo de retenci\u00f3n. Estos elementos, intr\u00ednsecos y extr\u00ednsecos al pr\u00e9stamo, deben evaluarse para determinar el mejor tipo de pr\u00e9stamo para la inversi\u00f3n.<\/p>\n\n\n\n<p class=\"gtfy-280\">Los pr\u00e9stamos basados en activos sobre inmuebles residenciales estabilizados ofrecen opciones de s\u00f3lo inter\u00e9s, tipo fijo y ARM. Cada uno de estos tipos se centra en el ratio de cobertura del NOI frente al servicio de la deuda.<\/p>\n\n\n\n<p class=\"gtfy-283\">Recuerde que el tipo de inter\u00e9s y el apalancamiento m\u00e1s competitivos se obtendr\u00e1n con pr\u00e9stamos que permitan una penalizaci\u00f3n por pago anticipado. El periodo de permanencia del inversor determinar\u00e1 el verdadero efecto de esta penalizaci\u00f3n en la rentabilidad de la inversi\u00f3n.<\/p>\n\n\n\n<p class=\"gtfy-286\">Un pr\u00e9stamo autoamortizable a 30 a\u00f1os se fija a un tipo predeterminado evaluado en el momento de la suscripci\u00f3n. El tipo permanece invariable a lo largo del plazo, independientemente de las condiciones del mercado. El t\u00e9rmino &#8220;tipo competitivo&#8221; significa realmente unos pocos puntos b\u00e1sicos entre prestamistas privados y no puntos porcentuales enteros. Los tipos de inter\u00e9s suben y bajan en todos los mercados crediticios y no entre uno o dos prestamistas.<\/p>\n\n\n\n<p class=\"gtfy-289\">Lo m\u00e1s probable es que los pr\u00e9stamos de s\u00f3lo intereses para dinero permanente garantizado por una propiedad estabilizada no sean para toda la vida del pr\u00e9stamo. El per\u00edodo de carencia podr\u00eda ser durante los primeros a\u00f1os. El pr\u00e9stamo comenzar\u00e1 a amortizarse al final del per\u00edodo de carencia. Aunque esta estructura puede aliviar temporalmente al inversor en los primeros a\u00f1os, estos pr\u00e9stamos suelen cotizarse con una LTV m\u00e1s baja y un tipo de inter\u00e9s m\u00e1s alto.<\/p>\n\n\n\n<p class=\"gtfy-292\">Un pr\u00e9stamo DSCR con la estructura ARM comenzar\u00e1 con un tipo m\u00e1s bajo que los pr\u00e9stamos fijos y de s\u00f3lo intereses. Aunque este tipo de pr\u00e9stamo puede resultar rentable para un inversor, la clave est\u00e1 en el momento oportuno y en prestar atenci\u00f3n a los detalles. Cuando finalice el periodo de intereses bajos, los ajustes se mantendr\u00e1n durante todo el plazo del pr\u00e9stamo.<\/p>\n\n\n\n<p class=\"gtfy-295\">Cuando un inversor se plantea un pr\u00e9stamo ARM, debe sopesar el per\u00edodo de los pagos fijos a bajo inter\u00e9s frente a la penalizaci\u00f3n por pago anticipado y el plan de salida. En esta situaci\u00f3n, la variable es la salida, y la inc\u00f3gnita son los tipos de mercado futuros. El \u00fanico componente que puede ajustarse es la salida del inversor.<\/p>\n\n\n\n<p class=\"gtfy-298\"><strong>Conclusi\u00f3n<\/strong><\/p>\n\n\n\n<p class=\"gtfy-301\">Los inversores experimentados necesitan opciones, y los prestamistas privados son la mejor fuente de opciones.<\/p>\n\n\n\n<p class=\"gtfy-304\">Los prestamistas privados mantendr\u00e1n la misma flexibilidad a la hora de estructurar el mejor pr\u00e9stamo a largo plazo para el inversor. Con cada oportunidad, las estrategias de inversi\u00f3n ser\u00e1n diferentes para el inversor y el prestamista.<\/p>\n\n\n\n<p class=\"gtfy-307\">El tipo de inter\u00e9s, las comisiones y los costes determinan el beneficio del prestamista. Este beneficio es fijo y viene ilustrado por la TAE. El beneficio del inversor permanece desconocido hasta que se vende el activo con un c\u00e1lculo retrospectivo de los flujos de caja.<\/p>\n\n\n\n<p class=\"gtfy-310\">Las estructuras de pr\u00e9stamo DSCR ofrecidas por los prestamistas privados mantendr\u00e1n la misma flexibilidad en cuanto a un periodo m\u00e1s corto entre la solicitud y el cierre. El principal factor de suscripci\u00f3n es el rendimiento de la propiedad, y la calificaci\u00f3n crediticia del inversor se utiliza \u00fanicamente para establecer el tipo de inter\u00e9s ofertado.<\/p>\n\n\n\n<p class=\"gtfy-313\">Los inversores que necesiten pr\u00e9stamos DSCR a largo plazo para sus propiedades estabilizadas deben buscar un prestamista privado con un proceso transparente y la flexibilidad para personalizar un pr\u00e9stamo espec\u00edfico para los objetivos del inversor.<\/p>\n\n\n\n<p class=\"gtfy-316\">Ok, eso es todo por hoy, hemos cubierto el tema de 9 elementos que afectan a los t\u00e9rminos de los Pr\u00e9stamos de Alquiler DSCR y esperamos que hayan disfrutado de la lectura.<\/p>","protected":false},"excerpt":{"rendered":"<p>Los prestamistas privados ofrecen pr\u00e9stamos DSCR (ratio de cobertura del servicio de la deuda) a los inversores con la estrategia de &#8220;comprar y mantener&#8221; dinero permanente a largo plazo en la estabilizaci\u00f3n. El programa de pr\u00e9stamos DSCR es una alternativa que los inversores pueden comparar con los programas de pr\u00e9stamos a largo plazo que ofrecen los prestamistas tradicionales. Este art\u00edculo dar\u00e1 una visi\u00f3n general de los nueve elementos que afectan a la suscripci\u00f3n de un prestamista privado de un pr\u00e9stamo DSCR. Amplend entiende que los inversores inmobiliarios residenciales necesitan entender c\u00f3mo los prestamistas privados eval\u00faan los m\u00e9ritos de un acuerdo y los factores para lograr condiciones competitivas. Puntos clave T\u00e9rminos definidos Gastos por encima de la l\u00ednea: los gastos de explotaci\u00f3n aplicados a los ingresos por alquiler para calcular el NOI. Gastos no operativos: los gastos no operativos aplicados a los ingresos por alquiler para calcular el flujo de caja, como el servicio de la deuda y la financiaci\u00f3n de las cuentas de reserva. Capital acumulado: los componentes del importe del pr\u00e9stamo y el capital del inversor para totalizar el valor de mercado de la propiedad. Los elementos decisivos Hay nueve elementos decisivos que los prestamistas privados utilizan para determinar el tipo y las condiciones de un pr\u00e9stamo DSCR. Estos elementos son Objetivos del pr\u00e9stamo DSCR La suscripci\u00f3n de un pr\u00e9stamo DSCR a largo plazo para inmuebles estabilizados es m\u00e1s diligente que la suscripci\u00f3n de un pr\u00e9stamo de adquisici\u00f3n y renovaci\u00f3n a corto plazo. Sin embargo, un prestamista privado mantiene su esp\u00edritu empresarial en este proceso, y el tiempo entre la solicitud y la financiaci\u00f3n sigue siendo m\u00e1s corto que el de un prestamista tradicional. Los objetivos de un pr\u00e9stamo DSCR son acortar el tiempo en que el inversor atiende el pr\u00e9stamo a corto plazo, de mayor inter\u00e9s, y obtener antes los beneficios del capital creado por las renovaciones. Teniendo esto en cuenta, repasemos cada uno de los elementos anteriores. Coeficiente de cobertura del servicio de la deuda Este es el ratio m\u00e1s importante que tiene en cuenta un prestamista privado a la hora de suscribir una propiedad estabilizada. La f\u00f3rmula de este ratio es NOI (ingresos netos de explotaci\u00f3n) \u00f7 ADS (servicio anual de la deuda) Por ejemplo, si el ADS (principal e intereses solamente) es de 24.000 $, o 2.000 $ al mes, y el NOI de la propiedad es de 30.000 $, o 2.500 $ al mes, entonces $30,000 \u00f7 $24,000 = 1.25 La traducci\u00f3n de este ratio es la disponibilidad de 1,25 $ de ingresos netos (alquiler menos gastos) por cada 1 $ de servicio de la deuda. Sin embargo, cuando un inversor realiza este c\u00e1lculo para su propia diligencia debida, debe prestar atenci\u00f3n a los pagos del pr\u00e9stamo que contienen la financiaci\u00f3n de una cuenta de garant\u00eda bloqueada para los impuestos sobre la propiedad y el seguro. Recuerde que los pagos hipotecarios del principal y los intereses no entran en la definici\u00f3n de gastos de explotaci\u00f3n, pero los impuestos sobre la propiedad y el seguro se cargan por encima de la l\u00ednea. Hay que tener cuidado para asegurarse de que estos gastos no se contabilizan dos veces: una vez por encima de la l\u00ednea como gastos y otra vez por debajo de la l\u00ednea como parte del servicio de la deuda. El ratio de cobertura de 1,25 calculado anteriormente est\u00e1 por encima del ratio objetivo est\u00e1ndar del sector de 1,15. Un prestamista privado ofrecer\u00e1 condiciones de pr\u00e9stamo competitivas a los inmuebles que superen su ratio objetivo. Cuanto mayor sea el ratio, menor ser\u00e1 el riesgo percibido. Apalancamiento El ratio de cobertura del servicio de la deuda es importante cuando un prestamista privado considera el apalancamiento. Cuando un prestamista percibe menos riesgo, est\u00e1 dispuesto a prestar m\u00e1s capital. El apalancamiento es un porcentaje del importe del pr\u00e9stamo respecto al valor de mercado de la propiedad. Este porcentaje tambi\u00e9n se conoce como relaci\u00f3n pr\u00e9stamo-valor (LTV). Un inversor recibir\u00e1 menos efectivo en un pr\u00e9stamo con una LTV del 60% que en un pr\u00e9stamo con una LTV del 70%. Cuanto mayor sea la LTV, m\u00e1s efectivo estar\u00e1 dispuesto a financiar un prestamista debido a la menor percepci\u00f3n del riesgo. El riesgo est\u00e1 relacionado con el ratio de cobertura de la deuda y el apalancamiento. La f\u00f3rmula para calcular el apalancamiento es Importe del pr\u00e9stamo \u00f7 Valor de mercado Por ejemplo, si el valor de mercado de una propiedad es de 200.000 $ y un prestamista est\u00e1 dispuesto a prestar hasta el 70%, entonces 200.000 $ x 0,7 = 140.000 $, entonces 140.000 $ \u00f7 200.000 $ = 0,7, es decir, el 70%. El t\u00e9rmino &#8220;pila de capital&#8221; en este ejemplo es la suma del importe del pr\u00e9stamo y el capital del inversor es la &#8220;pila&#8221; que comprende el valor total de mercado. Para ilustrarlo: $140,000 Monto del pr\u065e\u00e9stamo +&nbsp; 60,000 Fondos propios de los inversores $200,000 Valor de mercado Por tanto, cuanto mayor sea el ratio LTV, m\u00e1s lejos en la pila de capital estar\u00e1 dispuesto a invertir un prestamista. Esto se traduce en una mayor salida de efectivo para el inversor debido a la menor percepci\u00f3n del riesgo. Con un pr\u00e9stamo DSCR garantizado por una propiedad estabilizada, los ratios de suscripci\u00f3n se basan en el valor de mercado, a diferencia de los pr\u00e9stamos a corto plazo, en los que los ratios se basan en el coste. Existe un capital incorporado cuando el valor de las mejoras supera los costes. Puntuaci\u00f3n crediticia La puntuaci\u00f3n crediticia del inversor tendr\u00e1 m\u00e1s peso a la hora de suscribir un pr\u00e9stamo DSCR que un pr\u00e9stamo de adquisici\u00f3n a corto plazo. La puntuaci\u00f3n crediticia es verificable y una forma r\u00e1pida de medir el riesgo para el prestamista. La puntuaci\u00f3n crediticia es el \u00fanico elemento de los nueve que se refiere directa y exclusivamente al inversor. Los otros ocho elementos se centran en el rendimiento de la propiedad y la tolerancia al riesgo del prestamista. La puntuaci\u00f3n crediticia afecta directamente al tipo de inter\u00e9s y al apalancamiento. La mejor manera de que un inversor<\/p>","protected":false},"author":3,"featured_media":2725,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_gutenify_countdown_timer_type":"fixed","_gutenify_countdown_timer_evergreen_hours":24,"_gutenify_countdown_timer_evergreen_minutes":0,"_gutenify_countdown_timer_date":"","_gutenify_countdown_timer_timezone":"US\/Eastern","_gutenify_countdown_timer_end_action":"none","_gutenify_countdown_timer_hide_selector":"","_gutenify_countdown_timer_redirect_url":"","content-type":"","footnotes":""},"categories":[47],"tags":[],"class_list":["post-2723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prestamos-privados"],"_links":{"self":[{"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/posts\/2723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/comments?post=2723"}],"version-history":[{"count":1,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/posts\/2723\/revisions"}],"predecessor-version":[{"id":2724,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/posts\/2723\/revisions\/2724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/media\/2725"}],"wp:attachment":[{"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/media?parent=2723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/categories?post=2723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amplend.net\/es\/wp-json\/wp\/v2\/tags?post=2723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}